{"id":14582,"date":"2024-05-01T11:27:34","date_gmt":"2024-05-01T17:27:34","guid":{"rendered":"http:\/\/imecaf.com\/blog\/?p=14582"},"modified":"2024-05-01T11:27:36","modified_gmt":"2024-05-01T17:27:36","slug":"como-usa-la-gente-las-computadoras","status":"publish","type":"post","link":"https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/","title":{"rendered":"C\u00f3mo usa la gente las computadoras"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Tiempo de lectura:<\/span> <span class=\"rt-time\"> &lt; 1<\/span> <span class=\"rt-label rt-postfix\">minuto<\/span><\/span>\n<p class=\"wp-block-paragraph\">\u00abLo que trato de hacer es tener en cuenta c\u00f3mo la gente usa las computadoras, cu\u00e1les son sus problemas y c\u00f3mo se pueden aplicar estas tecnolog\u00edas a esos problemas. Luego trato de indicar a los distintos grupos de productos que act\u00faen en funci\u00f3n de esta informaci\u00f3n.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">John Edward Warnock (1940-2023) Cient\u00edfico de la computaci\u00f3n, inventor, empresario tecnol\u00f3gico y fil\u00e1ntropo estadounidense co-fundador de Adobe Systems Inc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLo que trato de hacer es tener en cuenta c\u00f3mo la gente usa las computadoras, cu\u00e1les son sus problemas y c\u00f3mo se pueden aplicar estas tecnolog\u00edas a esos problemas. Luego trato de indicar a los distintos grupos de productos que act\u00faen en funci\u00f3n de esta informaci\u00f3n.\u00bb John Edward Warnock (1940-2023) Cient\u00edfico de la computaci\u00f3n, inventor, &#8230; <a title=\"C\u00f3mo usa la gente las computadoras\" class=\"read-more\" href=\"https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/\">Leer m\u00e1s <span class=\"screen-reader-text\">C\u00f3mo usa la gente las computadoras<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,552],"tags":[2673,3604,19,8873,8868,1184,2175,10433,569,4427,1140,2462],"class_list":["post-14582","post","type-post","status-publish","format-standard","hentry","category-computacion","category-frases-celebres-computacion","tag-actuar","tag-aplicar","tag-blog-imecaf","tag-computacion","tag-frase-celebre-2","tag-gente","tag-informacion","tag-john-warnock","tag-problemas","tag-productos","tag-tecnologia","tag-usar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo usa la gente las computadoras - IMECAF - Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo usa la gente las computadoras - IMECAF - Blog\" \/>\n<meta property=\"og:description\" content=\"\u00abLo que trato de hacer es tener en cuenta c\u00f3mo la gente usa las computadoras, cu\u00e1les son sus problemas y c\u00f3mo se pueden aplicar estas tecnolog\u00edas a esos problemas. Luego trato de indicar a los distintos grupos de productos que act\u00faen en funci\u00f3n de esta informaci\u00f3n.\u00bb John Edward Warnock (1940-2023) Cient\u00edfico de la computaci\u00f3n, inventor, ... Leer m\u00e1s C\u00f3mo usa la gente las computadoras\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/\" \/>\n<meta property=\"og:site_name\" content=\"IMECAF - Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IMECAF\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-01T17:27:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-01T17:27:36+00:00\" \/>\n<meta name=\"author\" content=\"Equipo de IMECAF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@imecaf\" \/>\n<meta name=\"twitter:site\" content=\"@imecaf\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo de IMECAF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2024\\\/05\\\/01\\\/como-usa-la-gente-las-computadoras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2024\\\/05\\\/01\\\/como-usa-la-gente-las-computadoras\\\/\"},\"author\":{\"name\":\"Equipo de IMECAF\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/person\\\/667fedea7027f0e801a0c67c34b9a884\"},\"headline\":\"C\u00f3mo usa la gente las computadoras\",\"datePublished\":\"2024-05-01T17:27:34+00:00\",\"dateModified\":\"2024-05-01T17:27:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2024\\\/05\\\/01\\\/como-usa-la-gente-las-computadoras\\\/\"},\"wordCount\":83,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\"},\"keywords\":[\"actuar\",\"aplicar\",\"blog IMECAF\",\"computacion\",\"frase celebre\",\"gente\",\"informacion\",\"john warnock\",\"problemas\",\"productos\",\"tecnologia\",\"usar\"],\"articleSection\":[\"Computaci\u00f3n\",\"Frases C\u00e9lebres\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/imecaf.com\\\/blog\\\/2024\\\/05\\\/01\\\/como-usa-la-gente-las-computadoras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2024\\\/05\\\/01\\\/como-usa-la-gente-las-computadoras\\\/\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2024\\\/05\\\/01\\\/como-usa-la-gente-las-computadoras\\\/\",\"name\":\"C\u00f3mo usa la gente las computadoras - IMECAF - Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#website\"},\"datePublished\":\"2024-05-01T17:27:34+00:00\",\"dateModified\":\"2024-05-01T17:27:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2024\\\/05\\\/01\\\/como-usa-la-gente-las-computadoras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/imecaf.com\\\/blog\\\/2024\\\/05\\\/01\\\/como-usa-la-gente-las-computadoras\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2024\\\/05\\\/01\\\/como-usa-la-gente-las-computadoras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo usa la gente las computadoras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\",\"name\":\"IMECAF\",\"description\":\"Un lugar para expresar y compartir inquietudes dentro del mundo de la educaci\u00f3n.\",\"publisher\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\",\"name\":\"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/wp-content\\\/uploads\\\/IMECAF.Logo_.25.png\",\"contentUrl\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/wp-content\\\/uploads\\\/IMECAF.Logo_.25.png\",\"width\":350,\"height\":350,\"caption\":\"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas\"},\"image\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IMECAF\",\"https:\\\/\\\/x.com\\\/imecaf\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/imecaf\\\/\",\"https:\\\/\\\/www.youtube.com\\\/imecaf\",\"https:\\\/\\\/www.instagram.com\\\/imecaf_mx\\\/\",\"https:\\\/\\\/imecaf.negocio.site\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/person\\\/667fedea7027f0e801a0c67c34b9a884\",\"name\":\"Equipo de IMECAF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g\",\"caption\":\"Equipo de IMECAF\"},\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/author\\\/mfonticoba\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo usa la gente las computadoras - IMECAF - Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo usa la gente las computadoras - IMECAF - Blog","og_description":"\u00abLo que trato de hacer es tener en cuenta c\u00f3mo la gente usa las computadoras, cu\u00e1les son sus problemas y c\u00f3mo se pueden aplicar estas tecnolog\u00edas a esos problemas. Luego trato de indicar a los distintos grupos de productos que act\u00faen en funci\u00f3n de esta informaci\u00f3n.\u00bb John Edward Warnock (1940-2023) Cient\u00edfico de la computaci\u00f3n, inventor, ... Leer m\u00e1s C\u00f3mo usa la gente las computadoras","og_url":"https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/","og_site_name":"IMECAF - Blog","article_publisher":"https:\/\/www.facebook.com\/IMECAF","article_published_time":"2024-05-01T17:27:34+00:00","article_modified_time":"2024-05-01T17:27:36+00:00","author":"Equipo de IMECAF","twitter_card":"summary_large_image","twitter_creator":"@imecaf","twitter_site":"@imecaf","twitter_misc":{"Escrito por":"Equipo de IMECAF","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/#article","isPartOf":{"@id":"https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/"},"author":{"name":"Equipo de IMECAF","@id":"https:\/\/imecaf.com\/blog\/#\/schema\/person\/667fedea7027f0e801a0c67c34b9a884"},"headline":"C\u00f3mo usa la gente las computadoras","datePublished":"2024-05-01T17:27:34+00:00","dateModified":"2024-05-01T17:27:36+00:00","mainEntityOfPage":{"@id":"https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/"},"wordCount":83,"commentCount":0,"publisher":{"@id":"https:\/\/imecaf.com\/blog\/#organization"},"keywords":["actuar","aplicar","blog IMECAF","computacion","frase celebre","gente","informacion","john warnock","problemas","productos","tecnologia","usar"],"articleSection":["Computaci\u00f3n","Frases C\u00e9lebres"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/","url":"https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/","name":"C\u00f3mo usa la gente las computadoras - IMECAF - Blog","isPartOf":{"@id":"https:\/\/imecaf.com\/blog\/#website"},"datePublished":"2024-05-01T17:27:34+00:00","dateModified":"2024-05-01T17:27:36+00:00","breadcrumb":{"@id":"https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/imecaf.com\/blog\/2024\/05\/01\/como-usa-la-gente-las-computadoras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/imecaf.com\/blog\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo usa la gente las computadoras"}]},{"@type":"WebSite","@id":"https:\/\/imecaf.com\/blog\/#website","url":"https:\/\/imecaf.com\/blog\/","name":"IMECAF","description":"Un lugar para expresar y compartir inquietudes dentro del mundo de la educaci\u00f3n.","publisher":{"@id":"https:\/\/imecaf.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imecaf.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/imecaf.com\/blog\/#organization","name":"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas","url":"https:\/\/imecaf.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/imecaf.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/imecaf.com\/blog\/wp-content\/uploads\/IMECAF.Logo_.25.png","contentUrl":"https:\/\/imecaf.com\/blog\/wp-content\/uploads\/IMECAF.Logo_.25.png","width":350,"height":350,"caption":"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas"},"image":{"@id":"https:\/\/imecaf.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IMECAF","https:\/\/x.com\/imecaf","https:\/\/www.linkedin.com\/company\/imecaf\/","https:\/\/www.youtube.com\/imecaf","https:\/\/www.instagram.com\/imecaf_mx\/","https:\/\/imecaf.negocio.site\/"]},{"@type":"Person","@id":"https:\/\/imecaf.com\/blog\/#\/schema\/person\/667fedea7027f0e801a0c67c34b9a884","name":"Equipo de IMECAF","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g","caption":"Equipo de IMECAF"},"url":"https:\/\/imecaf.com\/blog\/author\/mfonticoba\/"}]}},"_links":{"self":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts\/14582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/comments?post=14582"}],"version-history":[{"count":0,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts\/14582\/revisions"}],"wp:attachment":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/media?parent=14582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/categories?post=14582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/tags?post=14582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}