{"id":20312,"date":"2026-04-01T09:15:52","date_gmt":"2026-04-01T15:15:52","guid":{"rendered":"http:\/\/imecaf.com\/blog\/?p=20312"},"modified":"2026-04-01T09:15:53","modified_gmt":"2026-04-01T15:15:53","slug":"programar-es-un-superpoder","status":"publish","type":"post","link":"https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/","title":{"rendered":"Programar es un superpoder"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Tiempo de lectura:<\/span> <span class=\"rt-time\"> &lt; 1<\/span> <span class=\"rt-label rt-postfix\">minuto<\/span><\/span>\n<p class=\"wp-block-paragraph\">\u00abLas computadoras facilitan nuestra vida cotidiana, pero nuestras posibilidades con la tecnolog\u00eda, incluso la imaginada por otros, son limitadas. La capacidad humana de ense\u00f1ar a las m\u00e1quinas cosas completamente nuevas \u2014la programaci\u00f3n\u2014 es, sin duda, un superpoder.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tobias L\u00fctke (1980- ) Emprendedor y piloto de carreras germano-canadiense, cofundador y director ejecutivo de Shopify.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLas computadoras facilitan nuestra vida cotidiana, pero nuestras posibilidades con la tecnolog\u00eda, incluso la imaginada por otros, son limitadas. La capacidad humana de ense\u00f1ar a las m\u00e1quinas cosas completamente nuevas \u2014la programaci\u00f3n\u2014 es, sin duda, un superpoder.\u00bb Tobias L\u00fctke (1980- ) Emprendedor y piloto de carreras germano-canadiense, cofundador y director ejecutivo de Shopify.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,552],"tags":[19,4161,8873,26,8868,1322,1663,2672,2507,12262,1140,12263,124],"class_list":["post-20312","post","type-post","status-publish","format-standard","hentry","category-computacion","category-frases-celebres-computacion","tag-blog-imecaf","tag-capacidad","tag-computacion","tag-ensenar","tag-frase-celebre-2","tag-humana","tag-maquina","tag-posibilidad","tag-programar","tag-superpoder","tag-tecnologia","tag-tobias-lutke","tag-vida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Programar es un superpoder - IMECAF - Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programar es un superpoder - IMECAF - Blog\" \/>\n<meta property=\"og:description\" content=\"\u00abLas computadoras facilitan nuestra vida cotidiana, pero nuestras posibilidades con la tecnolog\u00eda, incluso la imaginada por otros, son limitadas. La capacidad humana de ense\u00f1ar a las m\u00e1quinas cosas completamente nuevas \u2014la programaci\u00f3n\u2014 es, sin duda, un superpoder.\u00bb Tobias L\u00fctke (1980- ) Emprendedor y piloto de carreras germano-canadiense, cofundador y director ejecutivo de Shopify.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/\" \/>\n<meta property=\"og:site_name\" content=\"IMECAF - Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IMECAF\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-01T15:15:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T15:15:53+00:00\" \/>\n<meta name=\"author\" content=\"Equipo de IMECAF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@imecaf\" \/>\n<meta name=\"twitter:site\" content=\"@imecaf\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo de IMECAF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2026\\\/04\\\/01\\\/programar-es-un-superpoder\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2026\\\/04\\\/01\\\/programar-es-un-superpoder\\\/\"},\"author\":{\"name\":\"Equipo de IMECAF\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/person\\\/667fedea7027f0e801a0c67c34b9a884\"},\"headline\":\"Programar es un superpoder\",\"datePublished\":\"2026-04-01T15:15:52+00:00\",\"dateModified\":\"2026-04-01T15:15:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2026\\\/04\\\/01\\\/programar-es-un-superpoder\\\/\"},\"wordCount\":61,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\"},\"keywords\":[\"blog IMECAF\",\"capacidad\",\"computacion\",\"ense\u00f1ar\",\"frase celebre\",\"humana\",\"maquina\",\"posibilidad\",\"programar\",\"superpoder\",\"tecnologia\",\"tobias l\u00fctke\",\"vida\"],\"articleSection\":[\"Computaci\u00f3n\",\"Frases C\u00e9lebres\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/imecaf.com\\\/blog\\\/2026\\\/04\\\/01\\\/programar-es-un-superpoder\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2026\\\/04\\\/01\\\/programar-es-un-superpoder\\\/\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2026\\\/04\\\/01\\\/programar-es-un-superpoder\\\/\",\"name\":\"Programar es un superpoder - IMECAF - Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#website\"},\"datePublished\":\"2026-04-01T15:15:52+00:00\",\"dateModified\":\"2026-04-01T15:15:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2026\\\/04\\\/01\\\/programar-es-un-superpoder\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/imecaf.com\\\/blog\\\/2026\\\/04\\\/01\\\/programar-es-un-superpoder\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2026\\\/04\\\/01\\\/programar-es-un-superpoder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programar es un superpoder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\",\"name\":\"IMECAF\",\"description\":\"Un lugar para expresar y compartir inquietudes dentro del mundo de la educaci\u00f3n.\",\"publisher\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\",\"name\":\"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/wp-content\\\/uploads\\\/IMECAF.Logo_.25.png\",\"contentUrl\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/wp-content\\\/uploads\\\/IMECAF.Logo_.25.png\",\"width\":350,\"height\":350,\"caption\":\"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas\"},\"image\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IMECAF\",\"https:\\\/\\\/x.com\\\/imecaf\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/imecaf\\\/\",\"https:\\\/\\\/www.youtube.com\\\/imecaf\",\"https:\\\/\\\/www.instagram.com\\\/imecaf_mx\\\/\",\"https:\\\/\\\/imecaf.negocio.site\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/person\\\/667fedea7027f0e801a0c67c34b9a884\",\"name\":\"Equipo de IMECAF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g\",\"caption\":\"Equipo de IMECAF\"},\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/author\\\/mfonticoba\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programar es un superpoder - IMECAF - Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/","og_locale":"es_ES","og_type":"article","og_title":"Programar es un superpoder - IMECAF - Blog","og_description":"\u00abLas computadoras facilitan nuestra vida cotidiana, pero nuestras posibilidades con la tecnolog\u00eda, incluso la imaginada por otros, son limitadas. La capacidad humana de ense\u00f1ar a las m\u00e1quinas cosas completamente nuevas \u2014la programaci\u00f3n\u2014 es, sin duda, un superpoder.\u00bb Tobias L\u00fctke (1980- ) Emprendedor y piloto de carreras germano-canadiense, cofundador y director ejecutivo de Shopify.","og_url":"https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/","og_site_name":"IMECAF - Blog","article_publisher":"https:\/\/www.facebook.com\/IMECAF","article_published_time":"2026-04-01T15:15:52+00:00","article_modified_time":"2026-04-01T15:15:53+00:00","author":"Equipo de IMECAF","twitter_card":"summary_large_image","twitter_creator":"@imecaf","twitter_site":"@imecaf","twitter_misc":{"Escrito por":"Equipo de IMECAF","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/#article","isPartOf":{"@id":"https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/"},"author":{"name":"Equipo de IMECAF","@id":"https:\/\/imecaf.com\/blog\/#\/schema\/person\/667fedea7027f0e801a0c67c34b9a884"},"headline":"Programar es un superpoder","datePublished":"2026-04-01T15:15:52+00:00","dateModified":"2026-04-01T15:15:53+00:00","mainEntityOfPage":{"@id":"https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/"},"wordCount":61,"commentCount":0,"publisher":{"@id":"https:\/\/imecaf.com\/blog\/#organization"},"keywords":["blog IMECAF","capacidad","computacion","ense\u00f1ar","frase celebre","humana","maquina","posibilidad","programar","superpoder","tecnologia","tobias l\u00fctke","vida"],"articleSection":["Computaci\u00f3n","Frases C\u00e9lebres"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/","url":"https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/","name":"Programar es un superpoder - IMECAF - Blog","isPartOf":{"@id":"https:\/\/imecaf.com\/blog\/#website"},"datePublished":"2026-04-01T15:15:52+00:00","dateModified":"2026-04-01T15:15:53+00:00","breadcrumb":{"@id":"https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/imecaf.com\/blog\/2026\/04\/01\/programar-es-un-superpoder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/imecaf.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Programar es un superpoder"}]},{"@type":"WebSite","@id":"https:\/\/imecaf.com\/blog\/#website","url":"https:\/\/imecaf.com\/blog\/","name":"IMECAF","description":"Un lugar para expresar y compartir inquietudes dentro del mundo de la educaci\u00f3n.","publisher":{"@id":"https:\/\/imecaf.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imecaf.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/imecaf.com\/blog\/#organization","name":"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas","url":"https:\/\/imecaf.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/imecaf.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/imecaf.com\/blog\/wp-content\/uploads\/IMECAF.Logo_.25.png","contentUrl":"https:\/\/imecaf.com\/blog\/wp-content\/uploads\/IMECAF.Logo_.25.png","width":350,"height":350,"caption":"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas"},"image":{"@id":"https:\/\/imecaf.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IMECAF","https:\/\/x.com\/imecaf","https:\/\/www.linkedin.com\/company\/imecaf\/","https:\/\/www.youtube.com\/imecaf","https:\/\/www.instagram.com\/imecaf_mx\/","https:\/\/imecaf.negocio.site\/"]},{"@type":"Person","@id":"https:\/\/imecaf.com\/blog\/#\/schema\/person\/667fedea7027f0e801a0c67c34b9a884","name":"Equipo de IMECAF","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g","caption":"Equipo de IMECAF"},"url":"https:\/\/imecaf.com\/blog\/author\/mfonticoba\/"}]}},"_links":{"self":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts\/20312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/comments?post=20312"}],"version-history":[{"count":1,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts\/20312\/revisions"}],"predecessor-version":[{"id":20313,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts\/20312\/revisions\/20313"}],"wp:attachment":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/media?parent=20312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/categories?post=20312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/tags?post=20312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}