{"id":4568,"date":"2015-02-18T08:45:30","date_gmt":"2015-02-18T14:45:30","guid":{"rendered":"http:\/\/www.imecaf.com\/blog\/?p=4568"},"modified":"2015-02-18T08:45:30","modified_gmt":"2015-02-18T14:45:30","slug":"no-es-la-respuesta-a-la-pregunta","status":"publish","type":"post","link":"https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/","title":{"rendered":"No es la respuesta a la pregunta"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Tiempo de lectura:<\/span> <span class=\"rt-time\"> &lt; 1<\/span> <span class=\"rt-label rt-postfix\">minuto<\/span><\/span><p style=\"text-align: justify;\">\u00abLa educaci\u00f3n no es la respuesta a la pregunta. La educaci\u00f3n es el medio para encontrar respuesta a todas las preguntas.\u00bb<\/p>\n<p style=\"text-align: justify;\">William Allin &#8211; Profesor de socioeconom\u00eda estadounidense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLa educaci\u00f3n no es la respuesta a la pregunta. La educaci\u00f3n es el medio para encontrar respuesta a todas las preguntas.\u00bb William Allin &#8211; Profesor de socioeconom\u00eda estadounidense.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[19,14,830,16,1649,5121,1627,6133],"class_list":["post-4568","post","type-post","status-publish","format-standard","hentry","category-frases-celebres","tag-blog-imecaf","tag-educacion-2","tag-encontrar","tag-frase-celebre","tag-medio","tag-pregunta","tag-respuesta","tag-william-allin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No es la respuesta a la pregunta - IMECAF - Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No es la respuesta a la pregunta - IMECAF - Blog\" \/>\n<meta property=\"og:description\" content=\"\u00abLa educaci\u00f3n no es la respuesta a la pregunta. La educaci\u00f3n es el medio para encontrar respuesta a todas las preguntas.\u00bb William Allin &#8211; Profesor de socioeconom\u00eda estadounidense.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/\" \/>\n<meta property=\"og:site_name\" content=\"IMECAF - Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IMECAF\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-18T14:45:30+00:00\" \/>\n<meta name=\"author\" content=\"Equipo de IMECAF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@imecaf\" \/>\n<meta name=\"twitter:site\" content=\"@imecaf\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo de IMECAF\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2015\\\/02\\\/18\\\/no-es-la-respuesta-a-la-pregunta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2015\\\/02\\\/18\\\/no-es-la-respuesta-a-la-pregunta\\\/\"},\"author\":{\"name\":\"Equipo de IMECAF\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/person\\\/667fedea7027f0e801a0c67c34b9a884\"},\"headline\":\"No es la respuesta a la pregunta\",\"datePublished\":\"2015-02-18T14:45:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2015\\\/02\\\/18\\\/no-es-la-respuesta-a-la-pregunta\\\/\"},\"wordCount\":38,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\"},\"keywords\":[\"blog IMECAF\",\"Educaci\u00f3n\",\"encontrar\",\"frase c\u00e9lebre\",\"medio\",\"pregunta\",\"respuesta\",\"william allin\"],\"articleSection\":[\"Frases C\u00e9lebres\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/imecaf.com\\\/blog\\\/2015\\\/02\\\/18\\\/no-es-la-respuesta-a-la-pregunta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2015\\\/02\\\/18\\\/no-es-la-respuesta-a-la-pregunta\\\/\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2015\\\/02\\\/18\\\/no-es-la-respuesta-a-la-pregunta\\\/\",\"name\":\"No es la respuesta a la pregunta - IMECAF - Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#website\"},\"datePublished\":\"2015-02-18T14:45:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2015\\\/02\\\/18\\\/no-es-la-respuesta-a-la-pregunta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/imecaf.com\\\/blog\\\/2015\\\/02\\\/18\\\/no-es-la-respuesta-a-la-pregunta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2015\\\/02\\\/18\\\/no-es-la-respuesta-a-la-pregunta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No es la respuesta a la pregunta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\",\"name\":\"IMECAF\",\"description\":\"Un lugar para expresar y compartir inquietudes dentro del mundo de la educaci\u00f3n.\",\"publisher\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\",\"name\":\"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/wp-content\\\/uploads\\\/IMECAF.Logo_.25.png\",\"contentUrl\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/wp-content\\\/uploads\\\/IMECAF.Logo_.25.png\",\"width\":350,\"height\":350,\"caption\":\"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas\"},\"image\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IMECAF\",\"https:\\\/\\\/x.com\\\/imecaf\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/imecaf\\\/\",\"https:\\\/\\\/www.youtube.com\\\/imecaf\",\"https:\\\/\\\/www.instagram.com\\\/imecaf_mx\\\/\",\"https:\\\/\\\/imecaf.negocio.site\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/person\\\/667fedea7027f0e801a0c67c34b9a884\",\"name\":\"Equipo de IMECAF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g\",\"caption\":\"Equipo de IMECAF\"},\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/author\\\/mfonticoba\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No es la respuesta a la pregunta - IMECAF - Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/","og_locale":"es_ES","og_type":"article","og_title":"No es la respuesta a la pregunta - IMECAF - Blog","og_description":"\u00abLa educaci\u00f3n no es la respuesta a la pregunta. La educaci\u00f3n es el medio para encontrar respuesta a todas las preguntas.\u00bb William Allin &#8211; Profesor de socioeconom\u00eda estadounidense.","og_url":"https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/","og_site_name":"IMECAF - Blog","article_publisher":"https:\/\/www.facebook.com\/IMECAF","article_published_time":"2015-02-18T14:45:30+00:00","author":"Equipo de IMECAF","twitter_card":"summary_large_image","twitter_creator":"@imecaf","twitter_site":"@imecaf","twitter_misc":{"Escrito por":"Equipo de IMECAF"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/#article","isPartOf":{"@id":"https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/"},"author":{"name":"Equipo de IMECAF","@id":"https:\/\/imecaf.com\/blog\/#\/schema\/person\/667fedea7027f0e801a0c67c34b9a884"},"headline":"No es la respuesta a la pregunta","datePublished":"2015-02-18T14:45:30+00:00","mainEntityOfPage":{"@id":"https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/"},"wordCount":38,"commentCount":0,"publisher":{"@id":"https:\/\/imecaf.com\/blog\/#organization"},"keywords":["blog IMECAF","Educaci\u00f3n","encontrar","frase c\u00e9lebre","medio","pregunta","respuesta","william allin"],"articleSection":["Frases C\u00e9lebres"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/","url":"https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/","name":"No es la respuesta a la pregunta - IMECAF - Blog","isPartOf":{"@id":"https:\/\/imecaf.com\/blog\/#website"},"datePublished":"2015-02-18T14:45:30+00:00","breadcrumb":{"@id":"https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/imecaf.com\/blog\/2015\/02\/18\/no-es-la-respuesta-a-la-pregunta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/imecaf.com\/blog\/"},{"@type":"ListItem","position":2,"name":"No es la respuesta a la pregunta"}]},{"@type":"WebSite","@id":"https:\/\/imecaf.com\/blog\/#website","url":"https:\/\/imecaf.com\/blog\/","name":"IMECAF","description":"Un lugar para expresar y compartir inquietudes dentro del mundo de la educaci\u00f3n.","publisher":{"@id":"https:\/\/imecaf.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imecaf.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/imecaf.com\/blog\/#organization","name":"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas","url":"https:\/\/imecaf.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/imecaf.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/imecaf.com\/blog\/wp-content\/uploads\/IMECAF.Logo_.25.png","contentUrl":"https:\/\/imecaf.com\/blog\/wp-content\/uploads\/IMECAF.Logo_.25.png","width":350,"height":350,"caption":"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas"},"image":{"@id":"https:\/\/imecaf.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IMECAF","https:\/\/x.com\/imecaf","https:\/\/www.linkedin.com\/company\/imecaf\/","https:\/\/www.youtube.com\/imecaf","https:\/\/www.instagram.com\/imecaf_mx\/","https:\/\/imecaf.negocio.site\/"]},{"@type":"Person","@id":"https:\/\/imecaf.com\/blog\/#\/schema\/person\/667fedea7027f0e801a0c67c34b9a884","name":"Equipo de IMECAF","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g","caption":"Equipo de IMECAF"},"url":"https:\/\/imecaf.com\/blog\/author\/mfonticoba\/"}]}},"_links":{"self":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts\/4568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/comments?post=4568"}],"version-history":[{"count":0,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts\/4568\/revisions"}],"wp:attachment":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/media?parent=4568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/categories?post=4568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/tags?post=4568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}