{"id":818,"date":"2012-10-23T17:34:12","date_gmt":"2012-10-23T17:34:12","guid":{"rendered":"http:\/\/www.imecaf.com\/blog\/?p=818"},"modified":"2014-10-08T13:05:21","modified_gmt":"2014-10-08T18:05:21","slug":"que-es-la-mision","status":"publish","type":"post","link":"https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/","title":{"rendered":"\u00bfQu\u00e9 es la Misi\u00f3n?"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Tiempo de lectura:<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">minutos<\/span><\/span><p style=\"text-align: justify;\">La misi\u00f3n es el motivo, prop\u00f3sito, fin o raz\u00f3n de ser de la existencia de una empresa u organizaci\u00f3n porque define: 1) lo que pretende cumplir en su entorno o sistema social en el que act\u00faa, 2) lo que pretende hacer, y 3) el para qui\u00e9n lo va a hacer; y es influenciada en momentos concretos por algunos elementos como: la historia de la organizaci\u00f3n, las preferencias de la gerencia y\/o de los propietarios, los factores externos o del entorno, los recursos disponibles, y sus capacidades distintivas.<\/p>\n<p style=\"text-align: justify;\">Complementando \u00e9sta definici\u00f3n, citamos un concepto de los autores Thompson y Strickland que dice: \u00abLo que una compa\u00f1\u00eda trata de hacer en la actualidad por sus clientes a menudo se califica como la misi\u00f3n de la compa\u00f1\u00eda. Una exposici\u00f3n de la misma a menudo es \u00fatil para ponderar el negocio en el cual se encuentra la compa\u00f1\u00eda y las necesidades de los clientes a quienes trata de servir\u00bb.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">La\u00a0misi\u00f3n\u00a0es un importante elemento de la planificaci\u00f3n estrat\u00e9gica porque es a partir de \u00e9sta\u00a0<em>que se formulan objetivos detallados que son los que guiar\u00e1n<\/em><em>\u00a0a la empresa u organizaci\u00f3n<\/em>. Por tanto, resulta imprescindible que mercad\u00f3logos, empresarios, emprendedores y directivos en general, conozcan cu\u00e1l es el\u00a0<em>concepto de misi\u00f3n<\/em>, y mejor a\u00fan, cu\u00e1les son los diferentes conceptos que proponen diversos expertos en temas de negocios, mercadotecnia y definici\u00f3n de t\u00e9rminos, para que tengan una visi\u00f3n m\u00e1s completa y aplicable del mismo.<\/p>\n<ul style=\"text-align: justify;\">\n<li>\n<div align=\"justify\">Para O. C. Ferrel y Geoffrey Hirt, autores del libro \u00abIntroducci\u00f3n a los Negocios en un Mundo Cambiante\u00bb, \u00ab<em>la\u00a0misi\u00f3n\u00a0de una organizaci\u00f3n es su prop\u00f3sito general. Responde a la pregunta \u00bfqu\u00e9 se supone que hace la organizaci\u00f3n?<\/em>\u00ab.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Enrique Franklin, en su libro \u00abOrganizaci\u00f3n de Empresas\u00bb, menciona acerca de la<em>misi\u00f3n<\/em>, que \u00ab<em>este enunciado sirve a la organizaci\u00f3n como gu\u00eda o marco de referencia para orientar sus acciones y enlazar lo deseado con lo posible<\/em>\u00ab.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Seg\u00fan Emilio D\u00edez de Castro, Julio Garc\u00eda, Francisca Mart\u00edn y Rafael Peri\u00e1\u00f1ez, autores del libro \u00abAdministraci\u00f3n y Direcci\u00f3n\u00bb, la \u00ab<em>misi\u00f3n\u00a0o prop\u00f3sito es el conjunto de razones fundamentales de la existencia de la compa\u00f1\u00eda. Contesta a la pregunta de porqu\u00e9 existe la compa\u00f1ia<\/em>\u00ab.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Para Jack Fleitman, autor del libro \u00abNegocios Exitosos\u00bb, el\u00a0<em>concepto de misi\u00f3n<\/em>\u00a0\u00ab<em>suele ser definido como el modo en que los empresarios l\u00edderes y ejecutivos deciden hacer realidad su visi\u00f3n<\/em>\u00ab.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Seg\u00fan el profesor Rafael Mu\u00f1iz Gonzales, autor del libro \u00abMarketing en el siglo XXI\u00bb, la<em>misi\u00f3n<\/em>\u00a0<em>\u00abdefine la raz\u00f3n de ser de la empresa, condiciona sus actividades presentes y futuras, proporciona unidad, sentido de direcci\u00f3n y gu\u00eda en la toma de decisiones estrat\u00e9gicas\u00bb<\/em>. Adem\u00e1s, seg\u00fan el mencionado autor, la\u00a0<em>misi\u00f3n<\/em>\u00a0proporciona una visi\u00f3n clara a la hora de definir en qu\u00e9 mercado esta la empresa, qui\u00e9nes son sus clientes y con qui\u00e9n esta compitiendo; por tanto y a su criterio,\u00a0<em>\u00absin una misi\u00f3n clara es imposible practicar la direcci\u00f3n estrat\u00e9gica\u00bb<\/em>.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Para Stanton, Etzel y Walker, autores del libro \u00abFundamentos de Marketing\u00bb, la\u00a0<em>misi\u00f3n<\/em>de una organizaci\u00f3n\u00a0<em>\u00abenuncia a que clientes sirve, que necesidades satisface y qu\u00e9 tipos de productos ofrece. Por su parte, una declaraci\u00f3n de misi\u00f3n indica, en t\u00e9rminos generales, los l\u00edmites de las actividades de la organizaci\u00f3n\u00bb<\/em>. Complementando \u00e9sta definici\u00f3n, los autores comentan que en la actualidad, las empresas que se atienen al concepto de marketing, expresan su\u00a0<em>misi\u00f3n<\/em>\u00a0con base en el cliente, de modo que refleje las necesidades que intentan satisfacer y los beneficios que proveen.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Finalmente, (y resulta conveniente tomarlo en cuenta) el \u00abDiccionario Enciclop\u00e9dico Oc\u00e9ano\u00bb define el t\u00e9rmino\u00a0<em>misi\u00f3n<\/em>\u00a0como la\u00a0<em>\u00abobra que una persona o colectividad se siente impelida a realizar\u00bb<\/em>.<\/div>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify;\" align=\"justify\">En este punto, y teniendo en cuenta las anteriores definiciones y conceptos, planteo de forma resumida el siguiente\u00a0<em>concepto de misi\u00f3n<\/em>:<\/p>\n<blockquote>\n<p align=\"justify\"><em>\u00abLa\u00a0misi\u00f3n\u00a0es el prop\u00f3sito general o raz\u00f3n de ser de la empresa u organizaci\u00f3n que enuncia a qu\u00e9 clientes sirve, qu\u00e9 necesidades satisface, qu\u00e9 tipos de productos ofrece y en general, cu\u00e1les son los l\u00edmites de sus actividades; por tanto, es aquello que todos los que componen la empresa u organizaci\u00f3n se sienten impelidos a realizar en el presente y futuro para hacer realidad la visi\u00f3n del empresario o de los ejecutivos, y por ello,\u00a0<\/em><em>la\u00a0misi\u00f3n\u00a0es el marco de referencia que orienta las acciones, enlaza lo deseado con lo posible, condiciona las actividades presentes y futuras, proporciona unidad, sentido de direcci\u00f3n y gu\u00eda en la toma de decisiones estrat\u00e9gicas\u00bb.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\" align=\"justify\">Aqu\u00ed, tambi\u00e9n cabe se\u00f1alar que para que la\u00a0<em>misi\u00f3n<\/em>\u00a0cumpla su importante funci\u00f3n, debe tener la capacidad de\u00a0mover a las personas\u00a0(propietarios, inversionistas, empleados, clientes y proveedores) a ser parte activa de lo que es la raz\u00f3n de ser o prop\u00f3sito general de la empresa u organizaci\u00f3n. Para ello, debe: 1) definir los principales campos de competencia de la compa\u00f1\u00eda, 2) ser motivante, 3) enfatizar en las principales pol\u00edticas a las que la empresa quiere honrar y 4) proporcionar a la compa\u00f1\u00eda direcci\u00f3n durante los pr\u00f3ximos 10 o 20 a\u00f1os.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Otro aspecto que se debe tomar en cuenta (porque suele ser motivo de discusiones al momento de definir la\u00a0<em>misi\u00f3n<\/em>\u00a0de la empresa u organizaci\u00f3n), es que\u00a0<em>la\u00a0misi\u00f3n\u00a0no necesita ser exclusiva de la empresa u organizaci\u00f3n porque sirve para guiar pero no necesariamente para diferenciar<\/em>.<\/p>\n<p style=\"text-align: justify;\"><em>Fuente:<\/em> <a rel=nofollow href=\"http:\/\/www.promonegocios.net\/mercadotecnia\/mision-concepto.htm\" target=\"_blank\">promonegocios.net<\/a><\/p>\n<p style=\"text-align: justify;\">Para conocer la definici\u00f3n de Visi\u00f3n, consulte el siguiente art\u00edculo: <a rel=nofollow href=http:\/\/www.imecaf.com\/blog\/2012\/10\/23\/que-es-la-vision\/ target=\"_blank\">\u00bfQu\u00e9 es la Visi\u00f3n?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La misi\u00f3n es el motivo, prop\u00f3sito, fin o raz\u00f3n de ser de la existencia de una empresa u organizaci\u00f3n porque define: 1) lo que pretende cumplir en su entorno o sistema social en el que act\u00faa, 2) lo que pretende hacer, y 3) el para qui\u00e9n lo va a hacer; y es influenciada en momentos &#8230; <a title=\"\u00bfQu\u00e9 es la Misi\u00f3n?\" class=\"read-more\" href=\"https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/\">Leer m\u00e1s <span class=\"screen-reader-text\">\u00bfQu\u00e9 es la Misi\u00f3n?<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[290],"tags":[73,19,312,801,802,799,800,803,804],"class_list":["post-818","post","type-post","status-publish","format-standard","hentry","category-articulos-administracion","tag-administracion-2","tag-blog-imecaf","tag-empresa","tag-mision-de-una-empresa","tag-mision-y-vision","tag-que-es-la-mision","tag-que-es-mision","tag-que-es-mision-y-vision","tag-vision-y-mision"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 es la Misi\u00f3n? - IMECAF - Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es la Misi\u00f3n? - IMECAF - Blog\" \/>\n<meta property=\"og:description\" content=\"La misi\u00f3n es el motivo, prop\u00f3sito, fin o raz\u00f3n de ser de la existencia de una empresa u organizaci\u00f3n porque define: 1) lo que pretende cumplir en su entorno o sistema social en el que act\u00faa, 2) lo que pretende hacer, y 3) el para qui\u00e9n lo va a hacer; y es influenciada en momentos ... Leer m\u00e1s \u00bfQu\u00e9 es la Misi\u00f3n?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/\" \/>\n<meta property=\"og:site_name\" content=\"IMECAF - Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IMECAF\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-23T17:34:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-10-08T18:05:21+00:00\" \/>\n<meta name=\"author\" content=\"Equipo de IMECAF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@imecaf\" \/>\n<meta name=\"twitter:site\" content=\"@imecaf\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo de IMECAF\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2012\\\/10\\\/23\\\/que-es-la-mision\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2012\\\/10\\\/23\\\/que-es-la-mision\\\/\"},\"author\":{\"name\":\"Equipo de IMECAF\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/person\\\/667fedea7027f0e801a0c67c34b9a884\"},\"headline\":\"\u00bfQu\u00e9 es la Misi\u00f3n?\",\"datePublished\":\"2012-10-23T17:34:12+00:00\",\"dateModified\":\"2014-10-08T18:05:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2012\\\/10\\\/23\\\/que-es-la-mision\\\/\"},\"wordCount\":988,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\"},\"keywords\":[\"administraci\u00f3n\",\"blog IMECAF\",\"empresa\",\"mision de una empresa\",\"mision y vision\",\"que es la mision\",\"que es mision\",\"que es mision y vision\",\"vision y mision\"],\"articleSection\":[\"Art\u00edculos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/imecaf.com\\\/blog\\\/2012\\\/10\\\/23\\\/que-es-la-mision\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2012\\\/10\\\/23\\\/que-es-la-mision\\\/\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2012\\\/10\\\/23\\\/que-es-la-mision\\\/\",\"name\":\"\u00bfQu\u00e9 es la Misi\u00f3n? - IMECAF - Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#website\"},\"datePublished\":\"2012-10-23T17:34:12+00:00\",\"dateModified\":\"2014-10-08T18:05:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2012\\\/10\\\/23\\\/que-es-la-mision\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/imecaf.com\\\/blog\\\/2012\\\/10\\\/23\\\/que-es-la-mision\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/2012\\\/10\\\/23\\\/que-es-la-mision\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es la Misi\u00f3n?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\",\"name\":\"IMECAF\",\"description\":\"Un lugar para expresar y compartir inquietudes dentro del mundo de la educaci\u00f3n.\",\"publisher\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\",\"name\":\"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/wp-content\\\/uploads\\\/IMECAF.Logo_.25.png\",\"contentUrl\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/wp-content\\\/uploads\\\/IMECAF.Logo_.25.png\",\"width\":350,\"height\":350,\"caption\":\"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas\"},\"image\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IMECAF\",\"https:\\\/\\\/x.com\\\/imecaf\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/imecaf\\\/\",\"https:\\\/\\\/www.youtube.com\\\/imecaf\",\"https:\\\/\\\/www.instagram.com\\\/imecaf_mx\\\/\",\"https:\\\/\\\/imecaf.negocio.site\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/person\\\/667fedea7027f0e801a0c67c34b9a884\",\"name\":\"Equipo de IMECAF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g\",\"caption\":\"Equipo de IMECAF\"},\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/author\\\/mfonticoba\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es la Misi\u00f3n? - IMECAF - Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es la Misi\u00f3n? - IMECAF - Blog","og_description":"La misi\u00f3n es el motivo, prop\u00f3sito, fin o raz\u00f3n de ser de la existencia de una empresa u organizaci\u00f3n porque define: 1) lo que pretende cumplir en su entorno o sistema social en el que act\u00faa, 2) lo que pretende hacer, y 3) el para qui\u00e9n lo va a hacer; y es influenciada en momentos ... Leer m\u00e1s \u00bfQu\u00e9 es la Misi\u00f3n?","og_url":"https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/","og_site_name":"IMECAF - Blog","article_publisher":"https:\/\/www.facebook.com\/IMECAF","article_published_time":"2012-10-23T17:34:12+00:00","article_modified_time":"2014-10-08T18:05:21+00:00","author":"Equipo de IMECAF","twitter_card":"summary_large_image","twitter_creator":"@imecaf","twitter_site":"@imecaf","twitter_misc":{"Escrito por":"Equipo de IMECAF","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/#article","isPartOf":{"@id":"https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/"},"author":{"name":"Equipo de IMECAF","@id":"https:\/\/imecaf.com\/blog\/#\/schema\/person\/667fedea7027f0e801a0c67c34b9a884"},"headline":"\u00bfQu\u00e9 es la Misi\u00f3n?","datePublished":"2012-10-23T17:34:12+00:00","dateModified":"2014-10-08T18:05:21+00:00","mainEntityOfPage":{"@id":"https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/"},"wordCount":988,"commentCount":0,"publisher":{"@id":"https:\/\/imecaf.com\/blog\/#organization"},"keywords":["administraci\u00f3n","blog IMECAF","empresa","mision de una empresa","mision y vision","que es la mision","que es mision","que es mision y vision","vision y mision"],"articleSection":["Art\u00edculos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/","url":"https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/","name":"\u00bfQu\u00e9 es la Misi\u00f3n? - IMECAF - Blog","isPartOf":{"@id":"https:\/\/imecaf.com\/blog\/#website"},"datePublished":"2012-10-23T17:34:12+00:00","dateModified":"2014-10-08T18:05:21+00:00","breadcrumb":{"@id":"https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/imecaf.com\/blog\/2012\/10\/23\/que-es-la-mision\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/imecaf.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es la Misi\u00f3n?"}]},{"@type":"WebSite","@id":"https:\/\/imecaf.com\/blog\/#website","url":"https:\/\/imecaf.com\/blog\/","name":"IMECAF","description":"Un lugar para expresar y compartir inquietudes dentro del mundo de la educaci\u00f3n.","publisher":{"@id":"https:\/\/imecaf.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imecaf.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/imecaf.com\/blog\/#organization","name":"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas","url":"https:\/\/imecaf.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/imecaf.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/imecaf.com\/blog\/wp-content\/uploads\/IMECAF.Logo_.25.png","contentUrl":"https:\/\/imecaf.com\/blog\/wp-content\/uploads\/IMECAF.Logo_.25.png","width":350,"height":350,"caption":"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas"},"image":{"@id":"https:\/\/imecaf.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IMECAF","https:\/\/x.com\/imecaf","https:\/\/www.linkedin.com\/company\/imecaf\/","https:\/\/www.youtube.com\/imecaf","https:\/\/www.instagram.com\/imecaf_mx\/","https:\/\/imecaf.negocio.site\/"]},{"@type":"Person","@id":"https:\/\/imecaf.com\/blog\/#\/schema\/person\/667fedea7027f0e801a0c67c34b9a884","name":"Equipo de IMECAF","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4b4242953c12937bd47e298d7922b4d01ffafe2955ce4235d318b8950782aa13?s=96&d=mm&r=g","caption":"Equipo de IMECAF"},"url":"https:\/\/imecaf.com\/blog\/author\/mfonticoba\/"}]}},"_links":{"self":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts\/818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/comments?post=818"}],"version-history":[{"count":0,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts\/818\/revisions"}],"wp:attachment":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/media?parent=818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/categories?post=818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/tags?post=818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}