{"id":5063,"count":3,"description":"","link":"https:\/\/imecaf.com\/blog\/tag\/miguel-de-cervantes-saavedra\/","name":"miguel de cervantes saavedra","slug":"miguel-de-cervantes-saavedra","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>miguel de cervantes saavedra archivos - IMECAF - Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imecaf.com\/blog\/tag\/miguel-de-cervantes-saavedra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"miguel de cervantes saavedra archivos - IMECAF - Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imecaf.com\/blog\/tag\/miguel-de-cervantes-saavedra\/\" \/>\n<meta property=\"og:site_name\" content=\"IMECAF - Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@imecaf\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/tag\\\/miguel-de-cervantes-saavedra\\\/\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/tag\\\/miguel-de-cervantes-saavedra\\\/\",\"name\":\"miguel de cervantes saavedra archivos - IMECAF - Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/tag\\\/miguel-de-cervantes-saavedra\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/tag\\\/miguel-de-cervantes-saavedra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"miguel de cervantes saavedra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\",\"name\":\"IMECAF\",\"description\":\"Un lugar para expresar y compartir inquietudes dentro del mundo de la educaci\u00f3n.\",\"publisher\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#organization\",\"name\":\"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/wp-content\\\/uploads\\\/IMECAF.Logo_.25.png\",\"contentUrl\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/wp-content\\\/uploads\\\/IMECAF.Logo_.25.png\",\"width\":350,\"height\":350,\"caption\":\"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas\"},\"image\":{\"@id\":\"https:\\\/\\\/imecaf.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IMECAF\",\"https:\\\/\\\/x.com\\\/imecaf\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/imecaf\\\/\",\"https:\\\/\\\/www.youtube.com\\\/imecaf\",\"https:\\\/\\\/www.instagram.com\\\/imecaf_mx\\\/\",\"https:\\\/\\\/imecaf.negocio.site\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"miguel de cervantes saavedra archivos - IMECAF - Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imecaf.com\/blog\/tag\/miguel-de-cervantes-saavedra\/","og_locale":"es_ES","og_type":"article","og_title":"miguel de cervantes saavedra archivos - IMECAF - Blog","og_url":"https:\/\/imecaf.com\/blog\/tag\/miguel-de-cervantes-saavedra\/","og_site_name":"IMECAF - Blog","twitter_card":"summary_large_image","twitter_site":"@imecaf","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/imecaf.com\/blog\/tag\/miguel-de-cervantes-saavedra\/","url":"https:\/\/imecaf.com\/blog\/tag\/miguel-de-cervantes-saavedra\/","name":"miguel de cervantes saavedra archivos - IMECAF - Blog","isPartOf":{"@id":"https:\/\/imecaf.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/imecaf.com\/blog\/tag\/miguel-de-cervantes-saavedra\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/imecaf.com\/blog\/tag\/miguel-de-cervantes-saavedra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/imecaf.com\/blog\/"},{"@type":"ListItem","position":2,"name":"miguel de cervantes saavedra"}]},{"@type":"WebSite","@id":"https:\/\/imecaf.com\/blog\/#website","url":"https:\/\/imecaf.com\/blog\/","name":"IMECAF","description":"Un lugar para expresar y compartir inquietudes dentro del mundo de la educaci\u00f3n.","publisher":{"@id":"https:\/\/imecaf.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imecaf.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/imecaf.com\/blog\/#organization","name":"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas","url":"https:\/\/imecaf.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/imecaf.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/imecaf.com\/blog\/wp-content\/uploads\/IMECAF.Logo_.25.png","contentUrl":"https:\/\/imecaf.com\/blog\/wp-content\/uploads\/IMECAF.Logo_.25.png","width":350,"height":350,"caption":"IMECAF - Instituto Mexicano de Contabilidad, Administraci\u00f3n y Finanzas"},"image":{"@id":"https:\/\/imecaf.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IMECAF","https:\/\/x.com\/imecaf","https:\/\/www.linkedin.com\/company\/imecaf\/","https:\/\/www.youtube.com\/imecaf","https:\/\/www.instagram.com\/imecaf_mx\/","https:\/\/imecaf.negocio.site\/"]}]}},"_links":{"self":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/tags\/5063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/imecaf.com\/blog\/wp-json\/wp\/v2\/posts?tags=5063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}